{"id":10999,"date":"2025-05-21T08:21:00","date_gmt":"2025-05-21T08:21:00","guid":{"rendered":"https:\/\/glkpower.com\/?page_id=10999"},"modified":"2026-04-09T14:18:04","modified_gmt":"2026-04-09T06:18:04","slug":"pd-power-bank","status":"publish","type":"page","link":"https:\/\/glkpower.com\/uk\/pd-power-bank\/","title":{"rendered":"PD Power Bank"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10999\" class=\"elementor elementor-10999\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-790f38a e-con-full e-flex e-con e-parent\" data-id=\"790f38a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3396470 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"3396470\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a046e8f6d7fc\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8604079 elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8604079\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/glkpower.com\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/glkpower.com\/products\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-arrow-forward\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Products<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-arrow-forward\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">PD Power Bank<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bb0ef7 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bb0ef7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d75548f\" data-id=\"d75548f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a28d60 elementor-widget elementor-widget-ld_fancy_image\" data-id=\"6a28d60\" data-element_type=\"widget\" data-widget_type=\"ld_fancy_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"lqd-imggrp-single d-block pos-rel \">\n\t\t\t<div class=\"lqd-imggrp-img-container d-inline-flex pos-rel align-items-center justify-content-center \">\n\t\t\t\t\t\t\t\t<figure class=\"w-100 pos-rel\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-6.jpg\" class=\"attachment-full size-full wp-image-11972\" alt=\"\" srcset=\"https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-6.jpg 800w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-6-300x300.jpg 300w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-6-150x150.jpg 150w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-6-12x12.jpg 12w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-6-320x320.jpg 320w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-6-760x760.jpg 760w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;trigger&quot;:&quot;firstChild&quot;,&quot;animationTarget&quot;:&quot;:scope &gt; .elementor-widget-wrap &gt; .elementor-element &gt; .elementor-widget-container, :scope &gt; .elementor-widget-wrap &gt; .elementor-section &gt; .elementor-container &gt; .elementor-column &gt; .elementor-widget-wrap &gt; .elementor-element:not(.lqd-el-has-inner-anim) &gt; .elementor-widget-container, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li&quot;,&quot;duration&quot;:1800,&quot;delay&quot;:180,&quot;ease&quot;:[&quot;power4.out&quot;],&quot;initValues&quot;:{&quot;y&quot;:&quot;35px&quot;,&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;},&quot;animations&quot;:{&quot;y&quot;:&quot;0px&quot;,&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6a8ce53\" data-id=\"6a8ce53\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae440f5 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"ae440f5\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a046e8f6f585\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h6 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h6\"  > Product Archives<\/h6>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6169a34 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"6169a34\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a046e8f6fa16\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Powering life, faster and smarter.<\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2497af elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"b2497af\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a046e8f6fe57\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > Our PD power banks combine intelligent charging with portability, delivering up to 22.5W or 18W fast output to keep your devices running on the go. With capacities ranging from 10,000mAh to 20,000mAh, they\u2019re designed for everyday carry and emergency backup.<\/p>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d53ac60 elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"d53ac60\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div id=\"ld_icon_box_d53ac60\" class=\"iconbox d-flex flex-grow-1 pos-rel align-items-center iconbox-side\"   >\n\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex   \"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-checkmark\"><\/i><\/div><\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Fast PD Charging (18W \/ 20W \/ 22.5W options) <\/h3>\t\t\t\t<p><\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46800e4 elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"46800e4\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div id=\"ld_icon_box_46800e4\" class=\"iconbox d-flex flex-grow-1 pos-rel align-items-center iconbox-side\"   >\n\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex   \"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-checkmark\"><\/i><\/div><\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Multiple output interfaces (USB, USB-C, Wireless*) <\/h3>\t\t\t\t<p><\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c0bd7b elementor-align-left elementor-widget elementor-widget-ld_icon_box\" data-id=\"4c0bd7b\" data-element_type=\"widget\" data-widget_type=\"ld_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<div id=\"ld_icon_box_4c0bd7b\" class=\"iconbox d-flex flex-grow-1 pos-rel align-items-center iconbox-side\"   >\n\n\t\t\t\t\n\t\t\t\t<div class=\"iconbox-icon-wrap  \"><div class=\"iconbox-icon-container d-inline-flex   \"><i aria-hidden=\"true\" class=\"lqd-icn-ess icon-ion-ios-checkmark\"><\/i><\/div><\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<h3 class=\"lqd-iconbox-heading \" >Ideal for mobile phones, tablets, laptop <\/h3>\t\t\t\t<p><\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb899bc elementor-mobile-align-justify elementor-widget elementor-widget-ld_button\" data-id=\"eb899bc\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a\n\t\t\t\thref=\"#send-message-form\"class=\"elementor-button btn btn-solid btn-lg btn-icon-right btn-hover-reveal btn-has-label\"\t\t\t>\n\t\t\t\t\t\t\t\t\t<span data-text=\"Get a quote\" class=\"btn-txt\">\n\t\t\t\t\t\tGet a quote\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-md-arrow-round-forward\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bd124ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bd124ff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e1fca3\" data-id=\"8e1fca3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b43e0f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4b43e0f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;trigger&quot;:&quot;firstChild&quot;,&quot;animationTarget&quot;:&quot;:scope &gt; .elementor-widget-wrap &gt; .elementor-element &gt; .elementor-widget-container, :scope &gt; .elementor-widget-wrap &gt; .elementor-section &gt; .elementor-container &gt; .elementor-column &gt; .elementor-widget-wrap &gt; .elementor-element:not(.lqd-el-has-inner-anim) &gt; .elementor-widget-container, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li&quot;,&quot;ease&quot;:[&quot;power4.out&quot;],&quot;initValues&quot;:{&quot;y&quot;:&quot;35px&quot;,&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;},&quot;animations&quot;:{&quot;y&quot;:&quot;0px&quot;,&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-113145a\" data-id=\"113145a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f28c8c elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"3f28c8c\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a046e8f768c0\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Product List<\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-040a165 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"040a165\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a046e8f76d9f\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > We offer a wide range of high-quality, fast-charging power banks.<\/p>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4a51cee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a51cee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bd5a65e\" data-id=\"bd5a65e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd84539 elementor-widget elementor-widget-ld_portfolio\" data-id=\"fd84539\" data-element_type=\"widget\" data-widget_type=\"ld_portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"lqd-pf-grid lqd-pf-grid-fd84539\"><div id=\"lqd-pf-grid-fd84539\" class=\"lqd-pf-row row d-flex flex-wrap lqd-pf-grid-fd84539\" data-liquid-masonry=\"true\" data-masonry-options='{ \"layoutMode\": \"packery\" }'><div class=\"lqd-pf-column col-md-4 col-sm-6 col-xs-12 col-sm-6 col-xs-12 masonry-item pd-power-bank\">\n\n\t<article id=\"post-14647\" class=\"lqd-pf-item lqd-pf-item-style-6 border-radius-6 p-3 pt-4 lqd-pf-dark post-14647 liquid-portfolio type-liquid-portfolio status-publish format-standard has-post-thumbnail hentry liquid-portfolio-category-pd-power-bank output-dc-port output-usb-c-port capacity-20001mah-50000mah\">\n\t\t<div class=\"lqd-pf-item-inner\">\n\n\t\t\t<div class=\"lqd-pf-img mb-3 pos-rel border-radius-10 overflow-hidden\">\n\t\t\t\t<figure>\n\t\t\t\t\t<figure class=\"w-100\"><img decoding=\"async\" width=\"748\" height=\"748\" src=\"https:\/\/glkpower.com\/wp-content\/uploads\/2026\/04\/2-748x748.jpg\" class=\"w-100 wp-post-image\" alt=\"\" srcset=\"https:\/\/glkpower.com\/wp-content\/uploads\/2026\/04\/2-748x748.jpg 748w, https:\/\/glkpower.com\/wp-content\/uploads\/2026\/04\/2-300x300.jpg 300w, https:\/\/glkpower.com\/wp-content\/uploads\/2026\/04\/2-1024x1024.jpg 1024w, https:\/\/glkpower.com\/wp-content\/uploads\/2026\/04\/2-150x150.jpg 150w, https:\/\/glkpower.com\/wp-content\/uploads\/2026\/04\/2-12x12.jpg 12w, https:\/\/glkpower.com\/wp-content\/uploads\/2026\/04\/2.jpg 1600w\" sizes=\"(max-width: 748px) 100vw, 748px\" \/><\/figure>\t\t\t\t<\/figure>\n\t\t\t\t<span class=\"lqd-pf-overlay-bg lqd-overlay d-flex align-items-center justify-content-center\">\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"lqd-pf-details\">\n\t\t\t\t<div class=\"d-flex justify-content-between\">\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-pf-title mt-0 align-items-center h5\">GP16<\/h2>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<ul class=\"reset-ul inline-nav lqd-pf-cat d-inline-flex pos-rel z-index-2\"><li><a href=\"https:\/\/glkpower.com\/uk\/portfolio-category\/pd-power-bank\/\">PD Power Bank<\/a><\/li><\/ul>\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/glkpower.com\/uk\/product\/gp16\/\"  class=\"lqd-overlay lqd-pf-overlay-link lqd-cc-label-trigger\" ><\/a>\n\t\t<\/div>\n\t<\/article>\n\n<\/div><div class=\"lqd-pf-column col-md-4 col-sm-6 col-xs-12 col-sm-6 col-xs-12 masonry-item pd-power-bank\">\n\n\t<article id=\"post-14412\" class=\"lqd-pf-item lqd-pf-item-style-6 border-radius-6 p-3 pt-4 lqd-pf-dark post-14412 liquid-portfolio type-liquid-portfolio status-publish format-standard has-post-thumbnail hentry liquid-portfolio-category-pd-power-bank output-dc-port output-usb-c-port output-wireless-charge capacity-20001mah-50000mah\">\n\t\t<div class=\"lqd-pf-item-inner\">\n\n\t\t\t<div class=\"lqd-pf-img mb-3 pos-rel border-radius-10 overflow-hidden\">\n\t\t\t\t<figure>\n\t\t\t\t\t<figure class=\"w-100\"><img decoding=\"async\" width=\"748\" height=\"748\" src=\"https:\/\/glkpower.com\/wp-content\/uploads\/2026\/03\/5-748x748.jpg\" class=\"w-100 wp-post-image\" alt=\"\" srcset=\"https:\/\/glkpower.com\/wp-content\/uploads\/2026\/03\/5-748x748.jpg 748w, https:\/\/glkpower.com\/wp-content\/uploads\/2026\/03\/5-300x300.jpg 300w, https:\/\/glkpower.com\/wp-content\/uploads\/2026\/03\/5-1024x1024.jpg 1024w, https:\/\/glkpower.com\/wp-content\/uploads\/2026\/03\/5-150x150.jpg 150w, https:\/\/glkpower.com\/wp-content\/uploads\/2026\/03\/5-12x12.jpg 12w, https:\/\/glkpower.com\/wp-content\/uploads\/2026\/03\/5.jpg 1600w\" sizes=\"(max-width: 748px) 100vw, 748px\" \/><\/figure>\t\t\t\t<\/figure>\n\t\t\t\t<span class=\"lqd-pf-overlay-bg lqd-overlay d-flex align-items-center justify-content-center\">\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"lqd-pf-details\">\n\t\t\t\t<div class=\"d-flex justify-content-between\">\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-pf-title mt-0 align-items-center h5\">GP12 Pro<\/h2>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<ul class=\"reset-ul inline-nav lqd-pf-cat d-inline-flex pos-rel z-index-2\"><li><a href=\"https:\/\/glkpower.com\/uk\/portfolio-category\/pd-power-bank\/\">PD Power Bank<\/a><\/li><\/ul>\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/glkpower.com\/uk\/product\/gp12-pro-2\/\"  class=\"lqd-overlay lqd-pf-overlay-link lqd-cc-label-trigger\" ><\/a>\n\t\t<\/div>\n\t<\/article>\n\n<\/div><div class=\"lqd-pf-column col-md-4 col-sm-6 col-xs-12 col-sm-6 col-xs-12 masonry-item pd-power-bank\">\n\n\t<article id=\"post-13987\" class=\"lqd-pf-item lqd-pf-item-style-6 border-radius-6 p-3 pt-4 lqd-pf-dark post-13987 liquid-portfolio type-liquid-portfolio status-publish format-standard has-post-thumbnail hentry liquid-portfolio-category-pd-power-bank output-dc-port output-usb-c-port output-wireless-charge capacity-20001mah-50000mah\">\n\t\t<div class=\"lqd-pf-item-inner\">\n\n\t\t\t<div class=\"lqd-pf-img mb-3 pos-rel border-radius-10 overflow-hidden\">\n\t\t\t\t<figure>\n\t\t\t\t\t<figure class=\"w-100\"><img loading=\"lazy\" decoding=\"async\" width=\"748\" height=\"748\" src=\"https:\/\/glkpower.com\/wp-content\/uploads\/2025\/12\/GP16-SE-2-748x748.jpg\" class=\"w-100 wp-post-image\" alt=\"\" srcset=\"https:\/\/glkpower.com\/wp-content\/uploads\/2025\/12\/GP16-SE-2-748x748.jpg 748w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/12\/GP16-SE-2-300x300.jpg 300w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/12\/GP16-SE-2-1024x1024.jpg 1024w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/12\/GP16-SE-2-150x150.jpg 150w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/12\/GP16-SE-2-12x12.jpg 12w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/12\/GP16-SE-2.jpg 1600w\" sizes=\"(max-width: 748px) 100vw, 748px\" \/><\/figure>\t\t\t\t<\/figure>\n\t\t\t\t<span class=\"lqd-pf-overlay-bg lqd-overlay d-flex align-items-center justify-content-center\">\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"lqd-pf-details\">\n\t\t\t\t<div class=\"d-flex justify-content-between\">\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-pf-title mt-0 align-items-center h5\">GP16 SE<\/h2>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<ul class=\"reset-ul inline-nav lqd-pf-cat d-inline-flex pos-rel z-index-2\"><li><a href=\"https:\/\/glkpower.com\/uk\/portfolio-category\/pd-power-bank\/\">PD Power Bank<\/a><\/li><\/ul>\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/glkpower.com\/uk\/product\/gp16-se\/\"  class=\"lqd-overlay lqd-pf-overlay-link lqd-cc-label-trigger\" ><\/a>\n\t\t<\/div>\n\t<\/article>\n\n<\/div><div class=\"lqd-pf-column col-md-4 col-sm-6 col-xs-12 col-sm-6 col-xs-12 masonry-item pd-power-bank\">\n\n\t<article id=\"post-13138\" class=\"lqd-pf-item lqd-pf-item-style-6 border-radius-6 p-3 pt-4 lqd-pf-dark post-13138 liquid-portfolio type-liquid-portfolio status-publish format-standard has-post-thumbnail hentry liquid-portfolio-category-pd-power-bank output-dc-port output-usb-c-port output-wireless-charge capacity-20001mah-50000mah\">\n\t\t<div class=\"lqd-pf-item-inner\">\n\n\t\t\t<div class=\"lqd-pf-img mb-3 pos-rel border-radius-10 overflow-hidden\">\n\t\t\t\t<figure>\n\t\t\t\t\t<figure class=\"w-100\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/GP13-powerbank-10.jpg\" class=\"w-100 wp-post-image\" alt=\"\" srcset=\"https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/GP13-powerbank-10.jpg 600w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/GP13-powerbank-10-300x300.jpg 300w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/GP13-powerbank-10-150x150.jpg 150w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/GP13-powerbank-10-12x12.jpg 12w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\t\t\t\t<\/figure>\n\t\t\t\t<span class=\"lqd-pf-overlay-bg lqd-overlay d-flex align-items-center justify-content-center\">\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"lqd-pf-details\">\n\t\t\t\t<div class=\"d-flex justify-content-between\">\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-pf-title mt-0 align-items-center h5\">GP13<\/h2>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<ul class=\"reset-ul inline-nav lqd-pf-cat d-inline-flex pos-rel z-index-2\"><li><a href=\"https:\/\/glkpower.com\/uk\/portfolio-category\/pd-power-bank\/\">PD Power Bank<\/a><\/li><\/ul>\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/glkpower.com\/uk\/product\/pd-100w-30000mah-power-bank\/\"  class=\"lqd-overlay lqd-pf-overlay-link lqd-cc-label-trigger\" ><\/a>\n\t\t<\/div>\n\t<\/article>\n\n<\/div><div class=\"lqd-pf-column col-md-4 col-sm-6 col-xs-12 col-sm-6 col-xs-12 masonry-item pd-power-bank\">\n\n\t<article id=\"post-13134\" class=\"lqd-pf-item lqd-pf-item-style-6 border-radius-6 p-3 pt-4 lqd-pf-dark post-13134 liquid-portfolio type-liquid-portfolio status-publish format-standard has-post-thumbnail hentry liquid-portfolio-category-pd-power-bank output-dc-port output-usb-c-port output-wireless-charge capacity-20001mah-50000mah\">\n\t\t<div class=\"lqd-pf-item-inner\">\n\n\t\t\t<div class=\"lqd-pf-img mb-3 pos-rel border-radius-10 overflow-hidden\">\n\t\t\t\t<figure>\n\t\t\t\t\t<figure class=\"w-100\"><img loading=\"lazy\" decoding=\"async\" width=\"748\" height=\"748\" src=\"https:\/\/glkpower.com\/wp-content\/uploads\/2025\/06\/20230504121152077adcfbd50c4398a2041c795d3b6b62-1-748x748.jpg\" class=\"w-100 wp-post-image\" alt=\"\" srcset=\"https:\/\/glkpower.com\/wp-content\/uploads\/2025\/06\/20230504121152077adcfbd50c4398a2041c795d3b6b62-1-748x748.jpg 748w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/06\/20230504121152077adcfbd50c4398a2041c795d3b6b62-1-300x300.jpg 300w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/06\/20230504121152077adcfbd50c4398a2041c795d3b6b62-1-150x150.jpg 150w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/06\/20230504121152077adcfbd50c4398a2041c795d3b6b62-1-12x12.jpg 12w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/06\/20230504121152077adcfbd50c4398a2041c795d3b6b62-1.jpg 800w\" sizes=\"(max-width: 748px) 100vw, 748px\" \/><\/figure>\t\t\t\t<\/figure>\n\t\t\t\t<span class=\"lqd-pf-overlay-bg lqd-overlay d-flex align-items-center justify-content-center\">\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"lqd-pf-details\">\n\t\t\t\t<div class=\"d-flex justify-content-between\">\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-pf-title mt-0 align-items-center h5\">GP12<\/h2>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<ul class=\"reset-ul inline-nav lqd-pf-cat d-inline-flex pos-rel z-index-2\"><li><a href=\"https:\/\/glkpower.com\/uk\/portfolio-category\/pd-power-bank\/\">PD Power Bank<\/a><\/li><\/ul>\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/glkpower.com\/uk\/product\/wireless-charger-10w-power-bank-24000mah-dc\/\"  class=\"lqd-overlay lqd-pf-overlay-link lqd-cc-label-trigger\" ><\/a>\n\t\t<\/div>\n\t<\/article>\n\n<\/div><div class=\"lqd-pf-column col-md-4 col-sm-6 col-xs-12 col-sm-6 col-xs-12 masonry-item pd-power-bank\">\n\n\t<article id=\"post-11966\" class=\"lqd-pf-item lqd-pf-item-style-6 border-radius-6 p-3 pt-4 lqd-pf-dark post-11966 liquid-portfolio type-liquid-portfolio status-publish format-standard has-post-thumbnail hentry liquid-portfolio-category-pd-power-bank output-usb-c-port capacity-10001mah-20000mah\">\n\t\t<div class=\"lqd-pf-item-inner\">\n\n\t\t\t<div class=\"lqd-pf-img mb-3 pos-rel border-radius-10 overflow-hidden\">\n\t\t\t\t<figure>\n\t\t\t\t\t<figure class=\"w-100\"><img loading=\"lazy\" decoding=\"async\" width=\"748\" height=\"748\" src=\"https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-2-748x748.jpg\" class=\"w-100 wp-post-image\" alt=\"\" srcset=\"https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-2-748x748.jpg 748w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-2-300x300.jpg 300w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-2-150x150.jpg 150w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-2-12x12.jpg 12w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-2-320x320.jpg 320w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-2-760x760.jpg 760w, https:\/\/glkpower.com\/wp-content\/uploads\/2025\/05\/YN-055P-2.jpg 800w\" sizes=\"(max-width: 748px) 100vw, 748px\" \/><\/figure>\t\t\t\t<\/figure>\n\t\t\t\t<span class=\"lqd-pf-overlay-bg lqd-overlay d-flex align-items-center justify-content-center\">\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"lqd-pf-details\">\n\t\t\t\t<div class=\"d-flex justify-content-between\">\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-pf-title mt-0 align-items-center h5\">YN-055P<\/h2>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<ul class=\"reset-ul inline-nav lqd-pf-cat d-inline-flex pos-rel z-index-2\"><li><a href=\"https:\/\/glkpower.com\/uk\/portfolio-category\/pd-power-bank\/\">PD Power Bank<\/a><\/li><\/ul>\t\t\t<\/div>\n\n\t\t\t<a href=\"https:\/\/glkpower.com\/uk\/product\/22-5w-portable-charger-power-bank\/\"  class=\"lqd-overlay lqd-pf-overlay-link lqd-cc-label-trigger\" ><\/a>\n\t\t<\/div>\n\t<\/article>\n\n<\/div><\/div><div class=\"page-nav text-center\"><nav aria-label=\"Page navigation\"><ul class=\"pagination\"><li><span aria-current=\"page\" class=\"page-numbers current\">1<\/span><\/li>\n\t<li><a class=\"page-numbers\" href=\"https:\/\/glkpower.com\/uk\/wp-json\/wp\/v2\/pages\/10999\/page\/2\/\">2<\/a><\/li>\n\t<li><a class=\"page-numbers\" href=\"https:\/\/glkpower.com\/uk\/wp-json\/wp\/v2\/pages\/10999\/page\/3\/\">3<\/a><\/li>\n\t<li><a class=\"next page-numbers\" href=\"https:\/\/glkpower.com\/uk\/wp-json\/wp\/v2\/pages\/10999\/page\/2\/\"><span aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"32\" viewBox=\"0 0 12 32\" style=\"width: 1em;height: 1em\"><path fill=\"currentColor\" d=\"M8.375 16L.437 8.062C-.125 7.5-.125 6.5.438 5.938s1.563-.563 2.126 0l9 9c.562.562.624 1.5.062 2.062l-9.063 9.063c-.312.312-.687.437-1.062.437s-.75-.125-1.063-.438c-.562-.562-.562-1.562 0-2.125z\"><\/path><\/svg><\/span><\/a><\/li><\/ul><\/nav><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-661bb9b elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"661bb9b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;trigger&quot;:&quot;firstChild&quot;,&quot;animationTarget&quot;:&quot;:scope &gt; .elementor-widget-wrap &gt; .elementor-element &gt; .elementor-widget-container, :scope &gt; .elementor-widget-wrap &gt; .elementor-section &gt; .elementor-container &gt; .elementor-column &gt; .elementor-widget-wrap &gt; .elementor-element:not(.lqd-el-has-inner-anim) &gt; .elementor-widget-container, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li&quot;,&quot;duration&quot;:1800,&quot;delay&quot;:180,&quot;ease&quot;:[&quot;power4.out&quot;],&quot;initValues&quot;:{&quot;y&quot;:&quot;35px&quot;,&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;},&quot;animations&quot;:{&quot;y&quot;:&quot;0px&quot;,&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9eb7513\" data-id=\"9eb7513\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7458071 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"7458071\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a046e8f96da9\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > FAQ<\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f090283 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"f090283\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a046e8f97226\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<p class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left p\"  > With nearly 20 years of experience, Merpower offers certified quality, reliable OEM services, and power solutions you can trust.<\/p>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a621f2d elementor-widget elementor-widget-ld_button\" data-id=\"a621f2d\" data-element_type=\"widget\" data-widget_type=\"ld_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\t<a\n\t\t\t\thref=\"#\" target=\"_blank\" rel=\"nofollow\"class=\"elementor-button btn btn-solid btn-lg btn-icon-right btn-hover-reveal btn-has-label\"\t\t\t>\n\t\t\t\t\t\t\t\t\t<span data-text=\"learn more\" class=\"btn-txt\">\n\t\t\t\t\t\tlearn more\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"btn-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"lqd-icn-ess icon-md-arrow-round-forward\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;trigger&quot;:&quot;firstChild&quot;,&quot;animationTarget&quot;:&quot;:scope &gt; .elementor-widget-wrap &gt; .elementor-element &gt; .elementor-widget-container, :scope &gt; .elementor-widget-wrap &gt; .elementor-section &gt; .elementor-container &gt; .elementor-column &gt; .elementor-widget-wrap &gt; .elementor-element:not(.lqd-el-has-inner-anim) &gt; .elementor-widget-container, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li&quot;,&quot;duration&quot;:1800,&quot;delay&quot;:180,&quot;ease&quot;:[&quot;power4.out&quot;],&quot;initValues&quot;:{&quot;y&quot;:&quot;35px&quot;,&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;},&quot;animations&quot;:{&quot;y&quot;:&quot;0px&quot;,&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6ed5253\" data-id=\"6ed5253\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99cd96a elementor-widget elementor-widget-ld_accordion\" data-id=\"99cd96a\" data-element_type=\"widget\" data-widget_type=\"ld_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"accordion accordion-title-bordered accordion-lg accordion-side-spacing accordion-title-bg-transparent accordion-title-round accordion-active-has-fill\" id=\"accordion-6a046e8f9a469\" role=\"tablist\" aria-multiselectable=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel  active\">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1611\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a046e8f9a469\" data-bs-parent=\"#accordion-6a046e8f9a469\" href=\"#collapse-1611\" data-target=\"#collapse-1611\" data-bs-target=\"#collapse-1611\"\n\t\t\t\t\taria-expanded=\"true\" aria-controls=\"collapse-1611\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">What Are Your Main Product?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-arrow-down\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-arrow-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1611\" class=\"accordion-collapse collapse  show\" data-bs-parent=\"#accordion-6a046e8f9a469\" role=\"tabpanel\" aria-labelledby=\"heading-1611\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p>Portable power stations, outdoor power bank, PD power supply,and other equipment suitable for outdoor end-users.<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel \">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1612\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a046e8f9a469\" data-bs-parent=\"#accordion-6a046e8f9a469\" href=\"#collapse-1612\" data-target=\"#collapse-1612\" data-bs-target=\"#collapse-1612\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1612\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\"> How Long Can I Get The Samples?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-arrow-down\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-arrow-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1612\" class=\"accordion-collapse collapse \" data-bs-parent=\"#accordion-6a046e8f9a469\" role=\"tabpanel\" aria-labelledby=\"heading-1612\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p>It will be shipped within one to five days after confirmation of the order.<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel \">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1613\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a046e8f9a469\" data-bs-parent=\"#accordion-6a046e8f9a469\" href=\"#collapse-1613\" data-target=\"#collapse-1613\" data-bs-target=\"#collapse-1613\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1613\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">What Are The Payment Terms For Sample?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-arrow-down\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-arrow-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1613\" class=\"accordion-collapse collapse \" data-bs-parent=\"#accordion-6a046e8f9a469\" role=\"tabpanel\" aria-labelledby=\"heading-1613\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p>You can pay Trade Assurance via T\/T , Paypal, Western union, etc.<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"accordion-item panel \">\n\n\t\t\t\t<div class=\"accordion-heading\" role=\"tab\" id=\"heading-1614\">\n\t\t\t\t<h4 class=\"accordion-title  tabindex=\"-1\">\t\t\t\t\t<a class=\"collapsed\" role=\"button\" data-toggle=\"collapse\" data-bs-toggle=\"collapse\"\n                    tabindex=\"0\"\n\t\t\t\t\tdata-parent=\"#accordion-6a046e8f9a469\" data-bs-parent=\"#accordion-6a046e8f9a469\" href=\"#collapse-1614\" data-target=\"#collapse-1614\" data-bs-target=\"#collapse-1614\"\n\t\t\t\t\taria-expanded=\"false\" aria-controls=\"collapse-1614\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-title-txt\">What Certifications Do The Products Have?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"accordion-expander\"><i class=\"lqd-icn-ess icon-ion-ios-arrow-down\"><\/i><i class=\"lqd-icn-ess icon-ion-ios-arrow-up\"><\/i><\/span>\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/h4>\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"collapse-1614\" class=\"accordion-collapse collapse \" data-bs-parent=\"#accordion-6a046e8f9a469\" role=\"tabpanel\" aria-labelledby=\"heading-1614\">\n\n\t\t\t\t<div class=\"accordion-content\">\n\t\t\t\t\t<p>We have MSDS, PSE, CCC, UN38.3, FCC, ISO 9001, BSCI ,CE, RoHS, and certifications for our products.<\/p>\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27a796d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27a796d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85ddb29\" data-id=\"85ddb29\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;trigger&quot;:&quot;firstChild&quot;,&quot;animationTarget&quot;:&quot;:scope &gt; .elementor-widget-container&quot;,&quot;duration&quot;:800,&quot;delay&quot;:100,&quot;ease&quot;:[&quot;power4.out&quot;],&quot;initValues&quot;:{&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;},&quot;animations&quot;:{&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-element elementor-element-769a1ba elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"769a1ba\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a046e8f9a98d\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Whether you need to modify an existing design or a completely new custom power solution,  <span style=\"color: #8cc63f\">contact us today!<\/span><\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-315b632 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"315b632\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9702583\" data-id=\"9702583\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7792dba elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7792dba\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-custom-animations=\"true\" data-ca-options=\"{&quot;addChildTimelines&quot;:false,&quot;trigger&quot;:&quot;firstChild&quot;,&quot;animationTarget&quot;:&quot;:scope &gt; .elementor-widget-wrap &gt; .elementor-element &gt; .elementor-widget-container, :scope &gt; .elementor-widget-wrap &gt; .elementor-section &gt; .elementor-container &gt; .elementor-column &gt; .elementor-widget-wrap &gt; .elementor-element:not(.lqd-el-has-inner-anim) &gt; .elementor-widget-container, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-lines .lqd-lines .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-words .lqd-words .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-hub_fancy_heading .lqd-split-chars .lqd-chars .split-inner, :scope &gt; .elementor-widget-wrap &gt; .elementor-widget-ld_custom_menu .lqd-fancy-menu &gt; ul &gt; li&quot;,&quot;duration&quot;:1800,&quot;delay&quot;:180,&quot;ease&quot;:[&quot;power4.out&quot;],&quot;initValues&quot;:{&quot;y&quot;:&quot;35px&quot;,&quot;opacity&quot;:0,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;},&quot;animations&quot;:{&quot;y&quot;:&quot;0px&quot;,&quot;opacity&quot;:1,&quot;transformOrigin&quot;:&quot;50% 50% 0px&quot;}}\" class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3984bbb\" data-id=\"3984bbb\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01ea2e9 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"01ea2e9\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a046e8f9ae02\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<h2 class=\"ld-fh-element d-inline-block pos-rel  elementor-heading-title lqd-highlight-classic lqd-highlight-grow-left h2\"  > Send Message<\/h2>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdb42b8 elementor-widget elementor-widget-hub_fancy_heading\" data-id=\"fdb42b8\" data-element_type=\"widget\" data-widget_type=\"hub_fancy_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div id=\"ld-fancy-heading-6a046e8f9b18a\" class=\"ld-fancy-heading pos-rel\">\n\t\t\t<div class=\"ld-fh-element d-inline-block pos-rel  lqd-highlight-classic lqd-highlight-grow-left div\"  > With nearly 20 years of experience, Merpower offers certified quality, reliable OEM services, and power solutions you can trust.<\/div>\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40d48c4 elementor-widget elementor-widget-shortcode\" data-id=\"40d48c4\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"10643\" class=\"elementor elementor-10643\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-1e70443 e-con-full e-flex e-con e-parent\" data-id=\"1e70443\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bdc8294 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"bdc8294\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Elementor_Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"10643\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"bdc8294\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"GP16SE - Merpower - Large Power Bank Manufacturers\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"14414\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tFull name\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-md  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-message elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tYour company\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[message]\" id=\"form-field-message\" class=\"elementor-field elementor-size-md  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tYour email address\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_6b0b0c1 elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_6b0b0c1\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tYour phone \/ whatsapp\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_6b0b0c1]\" id=\"form-field-field_6b0b0c1\" class=\"elementor-field elementor-size-md  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_e18eb26 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_e18eb26\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tSelect a product\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-caret-down\" viewBox=\"0 0 571.4 571.4\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M571 393Q571 407 561 418L311 668Q300 679 286 679T261 668L11 418Q0 407 0 393T11 368 36 357H536Q550 357 561 368T571 393Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_e18eb26]\" id=\"form-field-field_e18eb26\" class=\"elementor-field-textual elementor-size-md\">\n\t\t\t\t\t\t\t\t\t<option value=\"None\">None<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP09\">GP09<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP10\">GP10<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP12\">GP12<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP13\">GP13<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP14\">GP14<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP16\">GP16<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP20\">GP20<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP25\">GP25<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP30\">GP30<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP35\">GP35<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP40\">GP40<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP45\">GP45<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP50\">GP50<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"GP70\">GP70<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-field_614731d elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_614731d\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMessage\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-md\" name=\"form_fields[field_614731d]\" id=\"form-field-field_614731d\" rows=\"4\" placeholder=\"We are professional power bank manfacturer in China. We support both OEM sevices. Please tel us as much inforation as you could, such as sizes, packaging, order quantity, destination port etc. We will offer the best price for you.\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_2015824 elementor-col-100 recaptcha_v3-inline\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_2015824\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LdjnWwrAAAAALto43ezf8OCSCdeB4awjq_ntc-0\" data-type=\"v3\" data-action=\"Form\" data-badge=\"inline\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Send Message<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Home Products PD Power Bank Product Archives Powering life, faster and smarter. Our PD power banks combine intelligent charging with portability, delivering up to 22.5W or 18W fast output to keep your devices running on the go. With capacities ranging from 10,000mAh to 20,000mAh, they\u2019re designed for everyday carry and emergency backup. Fast PD Charging [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10999","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/glkpower.com\/uk\/wp-json\/wp\/v2\/pages\/10999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/glkpower.com\/uk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/glkpower.com\/uk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/glkpower.com\/uk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/glkpower.com\/uk\/wp-json\/wp\/v2\/comments?post=10999"}],"version-history":[{"count":5,"href":"https:\/\/glkpower.com\/uk\/wp-json\/wp\/v2\/pages\/10999\/revisions"}],"predecessor-version":[{"id":14688,"href":"https:\/\/glkpower.com\/uk\/wp-json\/wp\/v2\/pages\/10999\/revisions\/14688"}],"wp:attachment":[{"href":"https:\/\/glkpower.com\/uk\/wp-json\/wp\/v2\/media?parent=10999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}